{"id":106,"date":"2022-03-02T14:00:15","date_gmt":"2022-03-02T14:00:15","guid":{"rendered":"https:\/\/fierljeppen.frl\/\/?page_id=106"},"modified":"2025-05-20T06:38:57","modified_gmt":"2025-05-20T06:38:57","slug":"nieuws","status":"publish","type":"page","link":"https:\/\/fierljeppen.frl\/de\/nieuws\/","title":{"rendered":"News"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-106","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nieuws - Frysk Ljeppers Boun<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fierljeppen.frl\/de\/nieuws\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nieuws - Frysk Ljeppers Boun\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fierljeppen.frl\/de\/nieuws\/\" \/>\n<meta property=\"og:site_name\" content=\"Frysk Ljeppers Boun\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fierljeppen\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T06:38:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@flb_fierljeppen\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/nieuws\\\/\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/nieuws\\\/\",\"name\":\"Nieuws - Frysk Ljeppers Boun\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#website\"},\"datePublished\":\"2022-03-02T14:00:15+00:00\",\"dateModified\":\"2025-05-20T06:38:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/nieuws\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fierljeppen.frl\\\/nieuws\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/nieuws\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fierljeppen.frl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nieuws\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#website\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/\",\"name\":\"Frysk Ljeppers Boun\",\"description\":\"It plak foar it fierljeppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fierljeppen.frl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#organization\",\"name\":\"Frysk ljeppers Boun\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/flb_2022\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/FLBlogo20134Transwit.png\",\"contentUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/flb_2022\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/FLBlogo20134Transwit.png\",\"width\":180,\"height\":180,\"caption\":\"Frysk ljeppers Boun\"},\"image\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fierljeppen\",\"https:\\\/\\\/x.com\\\/flb_fierljeppen\",\"https:\\\/\\\/www.instagram.com\\\/fryskljeppersboun\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FierljeppenFriesland\\\/featured\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nieuws - Frysk Ljeppers Boun","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fierljeppen.frl\/de\/nieuws\/","og_locale":"de_DE","og_type":"article","og_title":"Nieuws - Frysk Ljeppers Boun","og_url":"https:\/\/fierljeppen.frl\/de\/nieuws\/","og_site_name":"Frysk Ljeppers Boun","article_publisher":"https:\/\/www.facebook.com\/fierljeppen","article_modified_time":"2025-05-20T06:38:57+00:00","twitter_card":"summary_large_image","twitter_site":"@flb_fierljeppen","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fierljeppen.frl\/nieuws\/","url":"https:\/\/fierljeppen.frl\/nieuws\/","name":"Nieuws - Frysk Ljeppers Boun","isPartOf":{"@id":"https:\/\/fierljeppen.frl\/#website"},"datePublished":"2022-03-02T14:00:15+00:00","dateModified":"2025-05-20T06:38:57+00:00","breadcrumb":{"@id":"https:\/\/fierljeppen.frl\/nieuws\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fierljeppen.frl\/nieuws\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fierljeppen.frl\/nieuws\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fierljeppen.frl\/"},{"@type":"ListItem","position":2,"name":"Nieuws"}]},{"@type":"WebSite","@id":"https:\/\/fierljeppen.frl\/#website","url":"https:\/\/fierljeppen.frl\/","name":"Frysk Ljeppers Boun","description":"It plak foar it fierljeppen","publisher":{"@id":"https:\/\/fierljeppen.frl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fierljeppen.frl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/fierljeppen.frl\/#organization","name":"Frysk ljeppers Boun","url":"https:\/\/fierljeppen.frl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/fierljeppen.frl\/#\/schema\/logo\/image\/","url":"https:\/\/fierljeppen.frl\/flb_2022\/wp-content\/uploads\/2022\/03\/FLBlogo20134Transwit.png","contentUrl":"https:\/\/fierljeppen.frl\/flb_2022\/wp-content\/uploads\/2022\/03\/FLBlogo20134Transwit.png","width":180,"height":180,"caption":"Frysk ljeppers Boun"},"image":{"@id":"https:\/\/fierljeppen.frl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fierljeppen","https:\/\/x.com\/flb_fierljeppen","https:\/\/www.instagram.com\/fryskljeppersboun\/","https:\/\/www.youtube.com\/user\/FierljeppenFriesland\/featured"]}]}},"_links":{"self":[{"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/pages\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/comments?post=106"}],"version-history":[{"count":6,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/pages\/106\/revisions"}],"predecessor-version":[{"id":3128,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/pages\/106\/revisions\/3128"}],"wp:attachment":[{"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/media?parent=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}