{"id":1879,"date":"2024-08-02T07:44:50","date_gmt":"2024-08-02T07:44:50","guid":{"rendered":"https:\/\/fierljeppen.frl\/?p=1879"},"modified":"2024-11-26T14:54:59","modified_gmt":"2024-11-26T14:54:59","slug":"nfb-reglementen","status":"publish","type":"post","link":"https:\/\/fierljeppen.frl\/de\/nfb-reglementen\/","title":{"rendered":"NFB Regelungen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2136,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regelement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NFB Reglementen - Frysk Ljeppers Boun<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fierljeppen.frl\/de\/nfb-reglementen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NFB Reglementen - Frysk Ljeppers Boun\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fierljeppen.frl\/de\/nfb-reglementen\/\" \/>\n<meta property=\"og:site_name\" content=\"Frysk Ljeppers Boun\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fierljeppen\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-02T07:44:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-26T14:54:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2022\/09\/Reglement_ICON.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yldau Reitsma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@flb_fierljeppen\" \/>\n<meta name=\"twitter:site\" content=\"@flb_fierljeppen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yldau Reitsma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/nfb-reglementen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/nfb-reglementen\\\/\"},\"author\":{\"name\":\"Yldau Reitsma\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/person\\\/692c072106295f73a74fe75a084f8bec\"},\"headline\":\"NFB Reglementen\",\"datePublished\":\"2024-08-02T07:44:50+00:00\",\"dateModified\":\"2024-11-26T14:54:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/nfb-reglementen\\\/\"},\"wordCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/nfb-reglementen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Reglement_ICON.jpg\",\"articleSection\":[\"Regelement\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/nfb-reglementen\\\/\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/nfb-reglementen\\\/\",\"name\":\"NFB Reglementen - Frysk Ljeppers Boun\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/nfb-reglementen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/nfb-reglementen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Reglement_ICON.jpg\",\"datePublished\":\"2024-08-02T07:44:50+00:00\",\"dateModified\":\"2024-11-26T14:54:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/nfb-reglementen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fierljeppen.frl\\\/nfb-reglementen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/nfb-reglementen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Reglement_ICON.jpg\",\"contentUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Reglement_ICON.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/nfb-reglementen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fierljeppen.frl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NFB Reglementen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#website\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/\",\"name\":\"Frysk Ljeppers Boun\",\"description\":\"It plak foar it fierljeppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fierljeppen.frl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#organization\",\"name\":\"Frysk ljeppers Boun\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/flb_2022\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/FLBlogo20134Transwit.png\",\"contentUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/flb_2022\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/FLBlogo20134Transwit.png\",\"width\":180,\"height\":180,\"caption\":\"Frysk ljeppers Boun\"},\"image\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fierljeppen\",\"https:\\\/\\\/x.com\\\/flb_fierljeppen\",\"https:\\\/\\\/www.instagram.com\\\/fryskljeppersboun\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FierljeppenFriesland\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/person\\\/692c072106295f73a74fe75a084f8bec\",\"name\":\"Yldau Reitsma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90977e12a2d2edc7c4cff4123f4fa0a4fd6c57f548d22648c06592be4c02dcc6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90977e12a2d2edc7c4cff4123f4fa0a4fd6c57f548d22648c06592be4c02dcc6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90977e12a2d2edc7c4cff4123f4fa0a4fd6c57f548d22648c06592be4c02dcc6?s=96&d=mm&r=g\",\"caption\":\"Yldau Reitsma\"},\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/de\\\/author\\\/flb_yldau\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NFB Reglementen - Frysk Ljeppers Boun","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fierljeppen.frl\/de\/nfb-reglementen\/","og_locale":"de_DE","og_type":"article","og_title":"NFB Reglementen - Frysk Ljeppers Boun","og_url":"https:\/\/fierljeppen.frl\/de\/nfb-reglementen\/","og_site_name":"Frysk Ljeppers Boun","article_publisher":"https:\/\/www.facebook.com\/fierljeppen","article_published_time":"2024-08-02T07:44:50+00:00","article_modified_time":"2024-11-26T14:54:59+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2022\/09\/Reglement_ICON.jpg","type":"image\/jpeg"}],"author":"Yldau Reitsma","twitter_card":"summary_large_image","twitter_creator":"@flb_fierljeppen","twitter_site":"@flb_fierljeppen","twitter_misc":{"Verfasst von":"Yldau Reitsma","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fierljeppen.frl\/nfb-reglementen\/#article","isPartOf":{"@id":"https:\/\/fierljeppen.frl\/nfb-reglementen\/"},"author":{"name":"Yldau Reitsma","@id":"https:\/\/fierljeppen.frl\/#\/schema\/person\/692c072106295f73a74fe75a084f8bec"},"headline":"NFB Reglementen","datePublished":"2024-08-02T07:44:50+00:00","dateModified":"2024-11-26T14:54:59+00:00","mainEntityOfPage":{"@id":"https:\/\/fierljeppen.frl\/nfb-reglementen\/"},"wordCount":2,"publisher":{"@id":"https:\/\/fierljeppen.frl\/#organization"},"image":{"@id":"https:\/\/fierljeppen.frl\/nfb-reglementen\/#primaryimage"},"thumbnailUrl":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2022\/09\/Reglement_ICON.jpg","articleSection":["Regelement"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/fierljeppen.frl\/nfb-reglementen\/","url":"https:\/\/fierljeppen.frl\/nfb-reglementen\/","name":"NFB Reglementen - Frysk Ljeppers Boun","isPartOf":{"@id":"https:\/\/fierljeppen.frl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fierljeppen.frl\/nfb-reglementen\/#primaryimage"},"image":{"@id":"https:\/\/fierljeppen.frl\/nfb-reglementen\/#primaryimage"},"thumbnailUrl":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2022\/09\/Reglement_ICON.jpg","datePublished":"2024-08-02T07:44:50+00:00","dateModified":"2024-11-26T14:54:59+00:00","breadcrumb":{"@id":"https:\/\/fierljeppen.frl\/nfb-reglementen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fierljeppen.frl\/nfb-reglementen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/fierljeppen.frl\/nfb-reglementen\/#primaryimage","url":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2022\/09\/Reglement_ICON.jpg","contentUrl":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2022\/09\/Reglement_ICON.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/fierljeppen.frl\/nfb-reglementen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fierljeppen.frl\/"},{"@type":"ListItem","position":2,"name":"NFB Reglementen"}]},{"@type":"WebSite","@id":"https:\/\/fierljeppen.frl\/#website","url":"https:\/\/fierljeppen.frl\/","name":"Frysk Ljeppers Boun","description":"It plak foar it fierljeppen","publisher":{"@id":"https:\/\/fierljeppen.frl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fierljeppen.frl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/fierljeppen.frl\/#organization","name":"Frysk ljeppers Boun","url":"https:\/\/fierljeppen.frl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/fierljeppen.frl\/#\/schema\/logo\/image\/","url":"https:\/\/fierljeppen.frl\/flb_2022\/wp-content\/uploads\/2022\/03\/FLBlogo20134Transwit.png","contentUrl":"https:\/\/fierljeppen.frl\/flb_2022\/wp-content\/uploads\/2022\/03\/FLBlogo20134Transwit.png","width":180,"height":180,"caption":"Frysk ljeppers Boun"},"image":{"@id":"https:\/\/fierljeppen.frl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fierljeppen","https:\/\/x.com\/flb_fierljeppen","https:\/\/www.instagram.com\/fryskljeppersboun\/","https:\/\/www.youtube.com\/user\/FierljeppenFriesland\/featured"]},{"@type":"Person","@id":"https:\/\/fierljeppen.frl\/#\/schema\/person\/692c072106295f73a74fe75a084f8bec","name":"Yldau Reitsma","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/90977e12a2d2edc7c4cff4123f4fa0a4fd6c57f548d22648c06592be4c02dcc6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90977e12a2d2edc7c4cff4123f4fa0a4fd6c57f548d22648c06592be4c02dcc6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90977e12a2d2edc7c4cff4123f4fa0a4fd6c57f548d22648c06592be4c02dcc6?s=96&d=mm&r=g","caption":"Yldau Reitsma"},"url":"https:\/\/fierljeppen.frl\/de\/author\/flb_yldau\/"}]}},"_links":{"self":[{"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/posts\/1879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/comments?post=1879"}],"version-history":[{"count":4,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/posts\/1879\/revisions"}],"predecessor-version":[{"id":2623,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/posts\/1879\/revisions\/2623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/media\/2136"}],"wp:attachment":[{"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/media?parent=1879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/categories?post=1879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/tags?post=1879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}