{"id":2798,"date":"2024-12-10T09:43:57","date_gmt":"2024-12-10T09:43:57","guid":{"rendered":"https:\/\/fierljeppen.frl\/?p=2798"},"modified":"2024-12-10T10:04:25","modified_gmt":"2024-12-10T10:04:25","slug":"fierljeppen-magazine-2013","status":"publish","type":"post","link":"https:\/\/fierljeppen.frl\/de\/fierljeppen-magazine-2013\/","title":{"rendered":"FIERLJEPPEN magazine 2013"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":2681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"class_list":["post-2798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fierljeppen-magazine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FIERLJEPPEN magazine 2013 - Frysk Ljeppers Boun<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fierljeppen.frl\/de\/fierljeppen-magazine-2013\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FIERLJEPPEN magazine 2013 - Frysk Ljeppers Boun\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fierljeppen.frl\/de\/fierljeppen-magazine-2013\/\" \/>\n<meta property=\"og:site_name\" content=\"Frysk Ljeppers Boun\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fierljeppen\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-10T09:43:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-10T10:04:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2024\/11\/FIERLJEPPEN-magazine_2013_omslag.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mark van Houten\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@flb_fierljeppen\" \/>\n<meta name=\"twitter:site\" content=\"@flb_fierljeppen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mark van Houten\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/fierljeppen-magazine-2013\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/fierljeppen-magazine-2013\\\/\"},\"author\":{\"name\":\"Mark van Houten\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/person\\\/d24eee548f0818a2713ef91733cd074a\"},\"headline\":\"FIERLJEPPEN magazine 2013\",\"datePublished\":\"2024-12-10T09:43:57+00:00\",\"dateModified\":\"2024-12-10T10:04:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/fierljeppen-magazine-2013\\\/\"},\"wordCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/fierljeppen-magazine-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/FIERLJEPPEN-magazine_2013_omslag.jpg\",\"articleSection\":[\"FIERLJEPPEN magazine\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/fierljeppen-magazine-2013\\\/\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/fierljeppen-magazine-2013\\\/\",\"name\":\"FIERLJEPPEN magazine 2013 - Frysk Ljeppers Boun\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/fierljeppen-magazine-2013\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/fierljeppen-magazine-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/FIERLJEPPEN-magazine_2013_omslag.jpg\",\"datePublished\":\"2024-12-10T09:43:57+00:00\",\"dateModified\":\"2024-12-10T10:04:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/fierljeppen-magazine-2013\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fierljeppen.frl\\\/fierljeppen-magazine-2013\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/fierljeppen-magazine-2013\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/FIERLJEPPEN-magazine_2013_omslag.jpg\",\"contentUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/FIERLJEPPEN-magazine_2013_omslag.jpg\",\"width\":800,\"height\":1132},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/fierljeppen-magazine-2013\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fierljeppen.frl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FIERLJEPPEN magazine 2013\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#website\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/\",\"name\":\"Frysk Ljeppers Boun\",\"description\":\"It plak foar it fierljeppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fierljeppen.frl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#organization\",\"name\":\"Frysk ljeppers Boun\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/flb_2022\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/FLBlogo20134Transwit.png\",\"contentUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/flb_2022\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/FLBlogo20134Transwit.png\",\"width\":180,\"height\":180,\"caption\":\"Frysk ljeppers Boun\"},\"image\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fierljeppen\",\"https:\\\/\\\/x.com\\\/flb_fierljeppen\",\"https:\\\/\\\/www.instagram.com\\\/fryskljeppersboun\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FierljeppenFriesland\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/person\\\/d24eee548f0818a2713ef91733cd074a\",\"name\":\"Mark van Houten\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e63f7d165777b8fa61ee18bdff175885301abaa7122431f72fa86e0cdf3cf749?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e63f7d165777b8fa61ee18bdff175885301abaa7122431f72fa86e0cdf3cf749?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e63f7d165777b8fa61ee18bdff175885301abaa7122431f72fa86e0cdf3cf749?s=96&d=mm&r=g\",\"caption\":\"Mark van Houten\"},\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/de\\\/author\\\/mark-van-houten\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FIERLJEPPEN magazine 2013 - Frysk Ljeppers Boun","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fierljeppen.frl\/de\/fierljeppen-magazine-2013\/","og_locale":"de_DE","og_type":"article","og_title":"FIERLJEPPEN magazine 2013 - Frysk Ljeppers Boun","og_url":"https:\/\/fierljeppen.frl\/de\/fierljeppen-magazine-2013\/","og_site_name":"Frysk Ljeppers Boun","article_publisher":"https:\/\/www.facebook.com\/fierljeppen","article_published_time":"2024-12-10T09:43:57+00:00","article_modified_time":"2024-12-10T10:04:25+00:00","og_image":[{"width":800,"height":1132,"url":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2024\/11\/FIERLJEPPEN-magazine_2013_omslag.jpg","type":"image\/jpeg"}],"author":"Mark van Houten","twitter_card":"summary_large_image","twitter_creator":"@flb_fierljeppen","twitter_site":"@flb_fierljeppen","twitter_misc":{"Verfasst von":"Mark van Houten","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fierljeppen.frl\/fierljeppen-magazine-2013\/#article","isPartOf":{"@id":"https:\/\/fierljeppen.frl\/fierljeppen-magazine-2013\/"},"author":{"name":"Mark van Houten","@id":"https:\/\/fierljeppen.frl\/#\/schema\/person\/d24eee548f0818a2713ef91733cd074a"},"headline":"FIERLJEPPEN magazine 2013","datePublished":"2024-12-10T09:43:57+00:00","dateModified":"2024-12-10T10:04:25+00:00","mainEntityOfPage":{"@id":"https:\/\/fierljeppen.frl\/fierljeppen-magazine-2013\/"},"wordCount":2,"publisher":{"@id":"https:\/\/fierljeppen.frl\/#organization"},"image":{"@id":"https:\/\/fierljeppen.frl\/fierljeppen-magazine-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2024\/11\/FIERLJEPPEN-magazine_2013_omslag.jpg","articleSection":["FIERLJEPPEN magazine"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/fierljeppen.frl\/fierljeppen-magazine-2013\/","url":"https:\/\/fierljeppen.frl\/fierljeppen-magazine-2013\/","name":"FIERLJEPPEN magazine 2013 - Frysk Ljeppers Boun","isPartOf":{"@id":"https:\/\/fierljeppen.frl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fierljeppen.frl\/fierljeppen-magazine-2013\/#primaryimage"},"image":{"@id":"https:\/\/fierljeppen.frl\/fierljeppen-magazine-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2024\/11\/FIERLJEPPEN-magazine_2013_omslag.jpg","datePublished":"2024-12-10T09:43:57+00:00","dateModified":"2024-12-10T10:04:25+00:00","breadcrumb":{"@id":"https:\/\/fierljeppen.frl\/fierljeppen-magazine-2013\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fierljeppen.frl\/fierljeppen-magazine-2013\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/fierljeppen.frl\/fierljeppen-magazine-2013\/#primaryimage","url":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2024\/11\/FIERLJEPPEN-magazine_2013_omslag.jpg","contentUrl":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2024\/11\/FIERLJEPPEN-magazine_2013_omslag.jpg","width":800,"height":1132},{"@type":"BreadcrumbList","@id":"https:\/\/fierljeppen.frl\/fierljeppen-magazine-2013\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fierljeppen.frl\/"},{"@type":"ListItem","position":2,"name":"FIERLJEPPEN magazine 2013"}]},{"@type":"WebSite","@id":"https:\/\/fierljeppen.frl\/#website","url":"https:\/\/fierljeppen.frl\/","name":"Frysk Ljeppers Boun","description":"It plak foar it fierljeppen","publisher":{"@id":"https:\/\/fierljeppen.frl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fierljeppen.frl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/fierljeppen.frl\/#organization","name":"Frysk ljeppers Boun","url":"https:\/\/fierljeppen.frl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/fierljeppen.frl\/#\/schema\/logo\/image\/","url":"https:\/\/fierljeppen.frl\/flb_2022\/wp-content\/uploads\/2022\/03\/FLBlogo20134Transwit.png","contentUrl":"https:\/\/fierljeppen.frl\/flb_2022\/wp-content\/uploads\/2022\/03\/FLBlogo20134Transwit.png","width":180,"height":180,"caption":"Frysk ljeppers Boun"},"image":{"@id":"https:\/\/fierljeppen.frl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fierljeppen","https:\/\/x.com\/flb_fierljeppen","https:\/\/www.instagram.com\/fryskljeppersboun\/","https:\/\/www.youtube.com\/user\/FierljeppenFriesland\/featured"]},{"@type":"Person","@id":"https:\/\/fierljeppen.frl\/#\/schema\/person\/d24eee548f0818a2713ef91733cd074a","name":"Mark van Houten","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e63f7d165777b8fa61ee18bdff175885301abaa7122431f72fa86e0cdf3cf749?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e63f7d165777b8fa61ee18bdff175885301abaa7122431f72fa86e0cdf3cf749?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63f7d165777b8fa61ee18bdff175885301abaa7122431f72fa86e0cdf3cf749?s=96&d=mm&r=g","caption":"Mark van Houten"},"url":"https:\/\/fierljeppen.frl\/de\/author\/mark-van-houten\/"}]}},"_links":{"self":[{"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/posts\/2798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/comments?post=2798"}],"version-history":[{"count":1,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/posts\/2798\/revisions"}],"predecessor-version":[{"id":2799,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/posts\/2798\/revisions\/2799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/media\/2681"}],"wp:attachment":[{"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/media?parent=2798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/categories?post=2798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fierljeppen.frl\/de\/wp-json\/wp\/v2\/tags?post=2798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}