{"id":1047,"date":"2022-09-27T10:49:47","date_gmt":"2022-09-27T10:49:47","guid":{"rendered":"https:\/\/fierljeppen.frl\/?p=1047"},"modified":"2025-02-19T18:55:57","modified_gmt":"2025-02-19T18:55:57","slug":"geschiedenis","status":"publish","type":"post","link":"https:\/\/fierljeppen.frl\/en\/geschiedenis\/","title":{"rendered":"History"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2128,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-algemeen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geschiedenis - Frysk Ljeppers Boun<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fierljeppen.frl\/en\/geschiedenis\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geschiedenis - Frysk Ljeppers Boun\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fierljeppen.frl\/en\/geschiedenis\/\" \/>\n<meta property=\"og:site_name\" content=\"Frysk Ljeppers Boun\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fierljeppen\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-27T10:49:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-19T18:55:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2022\/09\/Geschiedenis_ICON.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yldau Reitsma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@flb_fierljeppen\" \/>\n<meta name=\"twitter:site\" content=\"@flb_fierljeppen\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yldau Reitsma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/geschiedenis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/geschiedenis\\\/\"},\"author\":{\"name\":\"Yldau Reitsma\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/person\\\/692c072106295f73a74fe75a084f8bec\"},\"headline\":\"Geschiedenis\",\"datePublished\":\"2022-09-27T10:49:47+00:00\",\"dateModified\":\"2025-02-19T18:55:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/geschiedenis\\\/\"},\"wordCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/geschiedenis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Geschiedenis_ICON.jpg\",\"articleSection\":[\"Algemeen\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/geschiedenis\\\/\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/geschiedenis\\\/\",\"name\":\"Geschiedenis - Frysk Ljeppers Boun\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/geschiedenis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/geschiedenis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Geschiedenis_ICON.jpg\",\"datePublished\":\"2022-09-27T10:49:47+00:00\",\"dateModified\":\"2025-02-19T18:55:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/geschiedenis\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fierljeppen.frl\\\/geschiedenis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/geschiedenis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Geschiedenis_ICON.jpg\",\"contentUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Geschiedenis_ICON.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/geschiedenis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fierljeppen.frl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geschiedenis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#website\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/\",\"name\":\"Frysk Ljeppers Boun\",\"description\":\"It plak foar it fierljeppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fierljeppen.frl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#organization\",\"name\":\"Frysk ljeppers Boun\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/flb_2022\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/FLBlogo20134Transwit.png\",\"contentUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/flb_2022\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/FLBlogo20134Transwit.png\",\"width\":180,\"height\":180,\"caption\":\"Frysk ljeppers Boun\"},\"image\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fierljeppen\",\"https:\\\/\\\/x.com\\\/flb_fierljeppen\",\"https:\\\/\\\/www.instagram.com\\\/fryskljeppersboun\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FierljeppenFriesland\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/person\\\/692c072106295f73a74fe75a084f8bec\",\"name\":\"Yldau Reitsma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90977e12a2d2edc7c4cff4123f4fa0a4fd6c57f548d22648c06592be4c02dcc6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90977e12a2d2edc7c4cff4123f4fa0a4fd6c57f548d22648c06592be4c02dcc6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/90977e12a2d2edc7c4cff4123f4fa0a4fd6c57f548d22648c06592be4c02dcc6?s=96&d=mm&r=g\",\"caption\":\"Yldau Reitsma\"},\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/en\\\/author\\\/flb_yldau\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geschiedenis - Frysk Ljeppers Boun","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fierljeppen.frl\/en\/geschiedenis\/","og_locale":"en_GB","og_type":"article","og_title":"Geschiedenis - Frysk Ljeppers Boun","og_url":"https:\/\/fierljeppen.frl\/en\/geschiedenis\/","og_site_name":"Frysk Ljeppers Boun","article_publisher":"https:\/\/www.facebook.com\/fierljeppen","article_published_time":"2022-09-27T10:49:47+00:00","article_modified_time":"2025-02-19T18:55:57+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2022\/09\/Geschiedenis_ICON.jpg","type":"image\/jpeg"}],"author":"Yldau Reitsma","twitter_card":"summary_large_image","twitter_creator":"@flb_fierljeppen","twitter_site":"@flb_fierljeppen","twitter_misc":{"Written by":"Yldau Reitsma","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fierljeppen.frl\/geschiedenis\/#article","isPartOf":{"@id":"https:\/\/fierljeppen.frl\/geschiedenis\/"},"author":{"name":"Yldau Reitsma","@id":"https:\/\/fierljeppen.frl\/#\/schema\/person\/692c072106295f73a74fe75a084f8bec"},"headline":"Geschiedenis","datePublished":"2022-09-27T10:49:47+00:00","dateModified":"2025-02-19T18:55:57+00:00","mainEntityOfPage":{"@id":"https:\/\/fierljeppen.frl\/geschiedenis\/"},"wordCount":1,"publisher":{"@id":"https:\/\/fierljeppen.frl\/#organization"},"image":{"@id":"https:\/\/fierljeppen.frl\/geschiedenis\/#primaryimage"},"thumbnailUrl":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2022\/09\/Geschiedenis_ICON.jpg","articleSection":["Algemeen"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/fierljeppen.frl\/geschiedenis\/","url":"https:\/\/fierljeppen.frl\/geschiedenis\/","name":"Geschiedenis - Frysk Ljeppers Boun","isPartOf":{"@id":"https:\/\/fierljeppen.frl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fierljeppen.frl\/geschiedenis\/#primaryimage"},"image":{"@id":"https:\/\/fierljeppen.frl\/geschiedenis\/#primaryimage"},"thumbnailUrl":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2022\/09\/Geschiedenis_ICON.jpg","datePublished":"2022-09-27T10:49:47+00:00","dateModified":"2025-02-19T18:55:57+00:00","breadcrumb":{"@id":"https:\/\/fierljeppen.frl\/geschiedenis\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fierljeppen.frl\/geschiedenis\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/fierljeppen.frl\/geschiedenis\/#primaryimage","url":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2022\/09\/Geschiedenis_ICON.jpg","contentUrl":"https:\/\/fierljeppen.frl\/wp-content\/uploads\/2022\/09\/Geschiedenis_ICON.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/fierljeppen.frl\/geschiedenis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fierljeppen.frl\/"},{"@type":"ListItem","position":2,"name":"Geschiedenis"}]},{"@type":"WebSite","@id":"https:\/\/fierljeppen.frl\/#website","url":"https:\/\/fierljeppen.frl\/","name":"Frysk Ljeppers Boun","description":"It plak foar it fierljeppen","publisher":{"@id":"https:\/\/fierljeppen.frl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fierljeppen.frl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/fierljeppen.frl\/#organization","name":"Frysk ljeppers Boun","url":"https:\/\/fierljeppen.frl\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/fierljeppen.frl\/#\/schema\/logo\/image\/","url":"https:\/\/fierljeppen.frl\/flb_2022\/wp-content\/uploads\/2022\/03\/FLBlogo20134Transwit.png","contentUrl":"https:\/\/fierljeppen.frl\/flb_2022\/wp-content\/uploads\/2022\/03\/FLBlogo20134Transwit.png","width":180,"height":180,"caption":"Frysk ljeppers Boun"},"image":{"@id":"https:\/\/fierljeppen.frl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fierljeppen","https:\/\/x.com\/flb_fierljeppen","https:\/\/www.instagram.com\/fryskljeppersboun\/","https:\/\/www.youtube.com\/user\/FierljeppenFriesland\/featured"]},{"@type":"Person","@id":"https:\/\/fierljeppen.frl\/#\/schema\/person\/692c072106295f73a74fe75a084f8bec","name":"Yldau Reitsma","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/90977e12a2d2edc7c4cff4123f4fa0a4fd6c57f548d22648c06592be4c02dcc6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/90977e12a2d2edc7c4cff4123f4fa0a4fd6c57f548d22648c06592be4c02dcc6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90977e12a2d2edc7c4cff4123f4fa0a4fd6c57f548d22648c06592be4c02dcc6?s=96&d=mm&r=g","caption":"Yldau Reitsma"},"url":"https:\/\/fierljeppen.frl\/en\/author\/flb_yldau\/"}]}},"_links":{"self":[{"href":"https:\/\/fierljeppen.frl\/en\/wp-json\/wp\/v2\/posts\/1047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fierljeppen.frl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fierljeppen.frl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fierljeppen.frl\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fierljeppen.frl\/en\/wp-json\/wp\/v2\/comments?post=1047"}],"version-history":[{"count":6,"href":"https:\/\/fierljeppen.frl\/en\/wp-json\/wp\/v2\/posts\/1047\/revisions"}],"predecessor-version":[{"id":2957,"href":"https:\/\/fierljeppen.frl\/en\/wp-json\/wp\/v2\/posts\/1047\/revisions\/2957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fierljeppen.frl\/en\/wp-json\/wp\/v2\/media\/2128"}],"wp:attachment":[{"href":"https:\/\/fierljeppen.frl\/en\/wp-json\/wp\/v2\/media?parent=1047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fierljeppen.frl\/en\/wp-json\/wp\/v2\/categories?post=1047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fierljeppen.frl\/en\/wp-json\/wp\/v2\/tags?post=1047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}