{"id":2401,"date":"2024-11-11T12:42:09","date_gmt":"2024-11-11T12:42:09","guid":{"rendered":"https:\/\/fierljeppen.frl\/?page_id=2401"},"modified":"2025-01-06T10:47:12","modified_gmt":"2025-01-06T10:47:12","slug":"over-ons","status":"publish","type":"page","link":"https:\/\/fierljeppen.frl\/fr\/over-ons\/","title":{"rendered":"Oer \u00fas"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2401","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Over ons - Frysk Ljeppers Boun<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fierljeppen.frl\/fr\/over-ons\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Over ons - Frysk Ljeppers Boun\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fierljeppen.frl\/fr\/over-ons\/\" \/>\n<meta property=\"og:site_name\" content=\"Frysk Ljeppers Boun\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fierljeppen\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-06T10:47:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@flb_fierljeppen\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/over-ons\\\/\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/over-ons\\\/\",\"name\":\"Over ons - Frysk Ljeppers Boun\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#website\"},\"datePublished\":\"2024-11-11T12:42:09+00:00\",\"dateModified\":\"2025-01-06T10:47:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/over-ons\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fierljeppen.frl\\\/over-ons\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/over-ons\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fierljeppen.frl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Over ons\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#website\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/\",\"name\":\"Frysk Ljeppers Boun\",\"description\":\"It plak foar it fierljeppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fierljeppen.frl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#organization\",\"name\":\"Frysk ljeppers Boun\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fierljeppen.frl\\\/flb_2022\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/FLBlogo20134Transwit.png\",\"contentUrl\":\"https:\\\/\\\/fierljeppen.frl\\\/flb_2022\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/FLBlogo20134Transwit.png\",\"width\":180,\"height\":180,\"caption\":\"Frysk ljeppers Boun\"},\"image\":{\"@id\":\"https:\\\/\\\/fierljeppen.frl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fierljeppen\",\"https:\\\/\\\/x.com\\\/flb_fierljeppen\",\"https:\\\/\\\/www.instagram.com\\\/fryskljeppersboun\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FierljeppenFriesland\\\/featured\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Over ons - Frysk Ljeppers Boun","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fierljeppen.frl\/fr\/over-ons\/","og_locale":"fr_FR","og_type":"article","og_title":"Over ons - Frysk Ljeppers Boun","og_url":"https:\/\/fierljeppen.frl\/fr\/over-ons\/","og_site_name":"Frysk Ljeppers Boun","article_publisher":"https:\/\/www.facebook.com\/fierljeppen","article_modified_time":"2025-01-06T10:47:12+00:00","twitter_card":"summary_large_image","twitter_site":"@flb_fierljeppen","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fierljeppen.frl\/over-ons\/","url":"https:\/\/fierljeppen.frl\/over-ons\/","name":"Over ons - Frysk Ljeppers Boun","isPartOf":{"@id":"https:\/\/fierljeppen.frl\/#website"},"datePublished":"2024-11-11T12:42:09+00:00","dateModified":"2025-01-06T10:47:12+00:00","breadcrumb":{"@id":"https:\/\/fierljeppen.frl\/over-ons\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fierljeppen.frl\/over-ons\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fierljeppen.frl\/over-ons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fierljeppen.frl\/"},{"@type":"ListItem","position":2,"name":"Over ons"}]},{"@type":"WebSite","@id":"https:\/\/fierljeppen.frl\/#website","url":"https:\/\/fierljeppen.frl\/","name":"Frysk Ljeppers Boun","description":"It plak foar it fierljeppen","publisher":{"@id":"https:\/\/fierljeppen.frl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fierljeppen.frl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fierljeppen.frl\/#organization","name":"Frysk ljeppers Boun","url":"https:\/\/fierljeppen.frl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fierljeppen.frl\/#\/schema\/logo\/image\/","url":"https:\/\/fierljeppen.frl\/flb_2022\/wp-content\/uploads\/2022\/03\/FLBlogo20134Transwit.png","contentUrl":"https:\/\/fierljeppen.frl\/flb_2022\/wp-content\/uploads\/2022\/03\/FLBlogo20134Transwit.png","width":180,"height":180,"caption":"Frysk ljeppers Boun"},"image":{"@id":"https:\/\/fierljeppen.frl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fierljeppen","https:\/\/x.com\/flb_fierljeppen","https:\/\/www.instagram.com\/fryskljeppersboun\/","https:\/\/www.youtube.com\/user\/FierljeppenFriesland\/featured"]}]}},"_links":{"self":[{"href":"https:\/\/fierljeppen.frl\/fr\/wp-json\/wp\/v2\/pages\/2401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fierljeppen.frl\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fierljeppen.frl\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fierljeppen.frl\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fierljeppen.frl\/fr\/wp-json\/wp\/v2\/comments?post=2401"}],"version-history":[{"count":3,"href":"https:\/\/fierljeppen.frl\/fr\/wp-json\/wp\/v2\/pages\/2401\/revisions"}],"predecessor-version":[{"id":2842,"href":"https:\/\/fierljeppen.frl\/fr\/wp-json\/wp\/v2\/pages\/2401\/revisions\/2842"}],"wp:attachment":[{"href":"https:\/\/fierljeppen.frl\/fr\/wp-json\/wp\/v2\/media?parent=2401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}